{"id":8439,"date":"2023-12-14T16:21:26","date_gmt":"2023-12-14T16:21:26","guid":{"rendered":"https:\/\/gmz.ltd\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\/"},"modified":"2024-08-13T06:57:57","modified_gmt":"2024-08-13T06:57:57","slug":"compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla","status":"publish","type":"post","link":"https:\/\/gmz.ltd\/fr\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\/","title":{"rendered":"Compostable et biod\u00e9gradable : Introduction des gobelets en papier \u00e0 rev\u00eatement PLA"},"content":{"rendered":"\n<nav class=\"wp-block-stackable-table-of-contents stk-block-table-of-contents stk-block stk-61398ef\" data-block-id=\"61398ef\"><p class=\"stk-table-of-contents__title\">Table des mati\u00e8res<\/p><ul class=\"stk-table-of-contents__table\"><li><a href=\"#what-is-pla\">Qu&rsquo;est-ce que le PLA ?<\/a><\/li><li><a href=\"#what-are-the-benefits-of-pla-coated-paper-cups\">Quels sont les avantages des gobelets en papier couch\u00e9s en PLA ?<\/a><ul><li><a href=\"#100-compostable\">1. 100% compostable<\/a><\/li><li><a href=\"#biodegradable\">2. Biod\u00e9gradable<\/a><\/li><li><a href=\"#reduces-carbon-footprint\">3. R\u00e9duction de l&#8217;empreinte carbone<\/a><\/li><li><a href=\"#insulated-and-durable\">4. Isolation et durabilit\u00e9<\/a><\/li><li><a href=\"#5-drink-contact-safe\">5. Boire en toute s\u00e9curit\u00e9<\/a><\/li><li><a href=\"#brand-promotion\">6. Promotion de la marque<\/a><\/li><li><a href=\"#boosts-sales\">7. Stimuler les ventes<\/a><\/li><\/ul><\/li><li><a href=\"#are-there-any-problems-with-pla\">Y a-t-il des probl\u00e8mes avec l&rsquo;APL ?<\/a><\/li><li><a href=\"#what-is-the-difference-between-pla-and-pe-coating\">Quelle est la diff\u00e9rence entre les gobelets en papier couch\u00e9s PLA et PE ?<\/a><\/li><\/ul><\/nav>\n\n<h2 class=\"wp-block-heading\" id=\"what-is-pla\" data-block-type=\"core\">Qu&rsquo;est-ce que le PLA ?<\/h2>\n\n<p class=\"wp-block-paragraph\">Les gobelets en papier couch\u00e9 PLA sont un type de gobelet jetable populaire, id\u00e9al pour les boissons chaudes. PLA signifie acide polylactique et est fabriqu\u00e9 \u00e0 partir de sources v\u00e9g\u00e9tales renouvelables, notamment le bambou et l&rsquo;amidon de canne \u00e0 sucre. Il s\u2019agit d\u2019un <a href=\"https:\/\/gmz.ltd\/fr\/etiquette-produit\/gobelets-ecologiques\/\">gobelet en papier hautement \u00e9cologique<\/a> , compostable et biod\u00e9gradable, id\u00e9al pour diverses entreprises d\u2019alimentation et de boissons qui proposent des boissons \u00e0 emporter aux clients.<\/p>\n\n<p class=\"wp-block-paragraph\">Les gobelets jetables en papier ont \u00e9t\u00e9 invent\u00e9s pour la premi\u00e8re fois en 1908 par Lawrence Luellen, qui a cr\u00e9\u00e9 l&rsquo;id\u00e9e de gobelets \u00e0 caf\u00e9 \u00e0 emporter. Il a utilis\u00e9 une doublure en cire pour isoler les gobelets et \u00e9viter les fuites, tout en restant pratique pour les voyageurs. Ces gobelets en papier n&rsquo;ont cess\u00e9 de gagner en popularit\u00e9 au fil des ans, \u00e0 mesure que s&rsquo;ouvraient des caf\u00e9s et des restaurants \u00e0 emporter servant des boissons chaudes et froides \u00e0 leurs clients.<\/p>\n\n<p class=\"wp-block-paragraph\">Le PLA a ensuite \u00e9t\u00e9 invent\u00e9 dans les ann\u00e9es 1930, mais son utilisation pour les emballages ne s&rsquo;est g\u00e9n\u00e9ralis\u00e9e que dans les ann\u00e9es 1980, car il \u00e9tait trop co\u00fbteux \u00e0 travailler. En 1989, le Dr Patrick R. Gruber a d\u00e9couvert qu&rsquo;il pouvait fabriquer du plastique PLA en utilisant de l&rsquo;amidon de ma\u00efs, ce qui a permis de r\u00e9duire consid\u00e9rablement les co\u00fbts de fabrication du PLA, qui s&rsquo;est ensuite progressivement popularis\u00e9. Ce n&rsquo;est qu&rsquo;en 2009 que les premiers gobelets en papier recouverts de PLA ont \u00e9t\u00e9 fabriqu\u00e9s, ce qui a d\u00e9clench\u00e9 une r\u00e9volution de produits \u00e9cologiques et biod\u00e9gradables qui a permis de r\u00e9duire consid\u00e9rablement les d\u00e9chets plastiques dans le monde au fil des ans.<\/p>\n\n<p class=\"wp-block-paragraph\">Le rev\u00eatement PLA sp\u00e9cialis\u00e9 recouvre les gobelets d&rsquo;une fine couche de plastique qui renforce les gobelets, \u00e9vite qu&rsquo;ils ne se d\u00e9trempent et emp\u00eache le liquide chaud de traverser le papier du gobelet, ce qui permet d&rsquo;obtenir le gobelet parfait pour les boissons chaudes qui peuvent \u00eatre emport\u00e9es par les clients en d\u00e9placement. Il s&rsquo;agit \u00e9galement d&rsquo;un isolant efficace qui permet de garder le contenu du gobelet chaud plus longtemps que les gobelets d\u00e9pourvus de doublure suppl\u00e9mentaire. Les clients n&rsquo;ont pas l&rsquo;impression de devoir se presser et peuvent savourer le contenu des gobelets en papier couch\u00e9 PLA \u00e0 leur propre rythme.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"what-are-the-benefits-of-pla-coated-paper-cups\" data-block-type=\"core\">Quels sont les avantages des gobelets en papier couch\u00e9s en PLA ?<\/h2>\n\n<h3 class=\"wp-block-heading\" id=\"100-compostable\" data-block-type=\"core\">1. 100% compostable<\/h3>\n\n<p class=\"wp-block-paragraph\">L&rsquo;un des principaux avantages des gobelets en papier rev\u00eatus de PLA est qu&rsquo;ils sont 100 % recyclables et compostables, contrairement \u00e0 d&rsquo;autres gobelets tels que les gobelets en papier rev\u00eatus de PE, qui ne le sont pas. Une fois utilis\u00e9s et recycl\u00e9s, les gobelets sont d\u00e9pos\u00e9s dans une fosse de compostage sp\u00e9ciale et n&rsquo;ont aucun effet n\u00e9gatif sur l&rsquo;environnement. Lorsque les gobelets se d\u00e9gradent, ils sont transform\u00e9s en compost ou en engrais, qui sont ensuite r\u00e9inject\u00e9s dans l&rsquo;environnement et utilis\u00e9s pour cr\u00e9er de la mati\u00e8re organique qui est r\u00e9utilis\u00e9e \u00e0 l&rsquo;infini. Les gobelets en PLA sont donc beaucoup plus \u00e9cologiques et constituent un choix populaire pour de nombreuses entreprises de boissons.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"biodegradable\" data-block-type=\"core\">2. Biod\u00e9gradable<\/h3>\n\n<p class=\"wp-block-paragraph\">Ces gobelets en papier recouverts de PLA sont \u00e9galement 100 % biod\u00e9gradables, ce qui signifie que les produits se d\u00e9composent naturellement \u00e0 l&rsquo;aide de micro-organismes, ne lib\u00e8rent aucune mati\u00e8re toxique et n&rsquo;ont donc aucun impact n\u00e9gatif sur l&rsquo;environnement. Vous vous demandez peut-\u00eatre ce qu&rsquo;il advient du rev\u00eatement en plastique PLA pendant cette p\u00e9riode, mais le PLA est \u00e9galement cr\u00e9\u00e9 \u00e0 partir de sources renouvelables et de mat\u00e9riaux biod\u00e9gradables, ce qui signifie que le plastique est \u00e9galement biod\u00e9gradable. Cela permet de r\u00e9duire la pollution et les \u00e9missions dans l&rsquo;atmosph\u00e8re caus\u00e9es par le traitement des d\u00e9chets. Il permet \u00e9galement de r\u00e9duire la quantit\u00e9 de d\u00e9chets mis en d\u00e9charge, puisqu&rsquo;ils peuvent \u00eatre compost\u00e9s.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"reduces-carbon-footprint\" data-block-type=\"core\">3. R\u00e9duction de l&#8217;empreinte carbone<\/h3>\n\n<p class=\"wp-block-paragraph\">Les gobelets en papier n\u00e9cessitent beaucoup moins d&rsquo;\u00e9nergie et de carburant lors de leur fabrication et de leur transport que les gobelets en plastique traditionnels, en raison de leur l\u00e9g\u00e8ret\u00e9 et de leur production respectueuse de l&rsquo;environnement. La production du rev\u00eatement PLA \u00e9met \u00e9galement 68 % d&rsquo;\u00e9missions de carbone en moins que le plastique ordinaire. Le <a href=\"https:\/\/www.biopapercups.co.uk\/biodegradable-paper-cup-recycling\/\" rel=\"nofollow\">processus de fabrication consomme 35 % d&rsquo;\u00e9nergie en moins que les plastiques \u00e0 base de p\u00e9trole<\/a>, ce qui r\u00e9duit efficacement votre empreinte carbone si vous optez pour des gobelets en papier enduits de PLA. Cela signifie qu&rsquo;il est \u00e9galement beaucoup plus rentable de produire des gobelets en papier recouverts de PLA et que le m\u00eame \u00e9quipement peut \u00eatre utilis\u00e9 \u00e0 la fois pour le PLA et le plastique ordinaire, de sorte qu&rsquo;il n&rsquo;y a pas de co\u00fbt suppl\u00e9mentaire pour de nouvelles machines.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"insulated-and-durable\" data-block-type=\"core\">4. Isolation et durabilit\u00e9<\/h3>\n\n<p class=\"wp-block-paragraph\">  L&rsquo;un des avantages les plus courants des gobelets en papier \u00e0 rev\u00eatement PLA est l&rsquo;isolation qu&rsquo;offre la couche de plastique. Indispensable pour les boissons chaudes, la couche PLA permet au contenu de la tasse de rester chaud plus longtemps. Il offre \u00e9galement un gobelet plus durable et plus solide qu&rsquo;un gobelet en papier biod\u00e9gradable sans rev\u00eatement int\u00e9rieur. Le rev\u00eatement en PLA renforce la structure du gobelet, ce qui en fait une option appropri\u00e9e pour les clients de la vente \u00e0 emporter. Les gobelets compostables sont durables et la doublure emp\u00eache tout liquide de s&rsquo;\u00e9couler ou de s&rsquo;infiltrer pour une protection accrue. En outre, les gobelets en papier sont l\u00e9gers et ce rev\u00eatement n&rsquo;ajoute pas de poids suppl\u00e9mentaire, ce qui convient aux clients qui transportent leurs gobelets \u00e0 emporter.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"5-drink-contact-safe\" data-block-type=\"core\">5. Boire en toute s\u00e9curit\u00e9<\/h3>\n\n<p class=\"wp-block-paragraph\">Les gobelets en papier rev\u00eatus de PLA ne r\u00e9agissent pas chimiquement avec le contenu du gobelet, ce qui signifie qu&rsquo;ils peuvent \u00eatre utilis\u00e9s sans danger pour les boissons. Le PLA est un mat\u00e9riau non toxique qui n\u00e9cessite un environnement de compostage pour se d\u00e9composer en dioxyde de carbone et en eau. Les gobelets en papier couch\u00e9 PLA annonc\u00e9s sur GMZ sont conformes aux r\u00e9glementations sur les aliments et les boissons et sont certifi\u00e9s DIN EN13432 en vertu des r\u00e9glementations sur le contact alimentaire de la FDA et de l&rsquo;UE. GMZ est \u00e9galement en mesure d&rsquo;imprimer le code de lot sur les gobelets compostables en PLA si vous avez besoin de retracer le processus de fabrication.<\/p>\n\n<div class=\"wp-block-query is-layout-flow wp-block-query-is-layout-flow\" data-block-type=\"core\"><ul class=\"columns-1 products-block-post-template wp-block-post-template is-layout-grid wp-container-core-post-template-is-layout-6b9527a3 wp-block-post-template-is-layout-grid\" data-block-type=\"core\"><li data-wp-context=\"woocommerce\/products::{&quot;productId&quot;:7847,&quot;variationId&quot;:null}\" data-wp-interactive=\"woocommerce\/products\" data-wp-key=\"product-item-7847\" class=\"wp-block-post post-7847 product type-product status-publish has-post-thumbnail product_cat-gobelets-en-papier product_cat-gobelets-en-papier-pour-boissons-chaudes product_tag-gobelets-ecologiques product_tag-gobelets-et-couvercles-pour-boissons-chaudes first instock shipping-taxable product-type-simple\">\n<div data-block-name=\"woocommerce\/product-image\" data-height=\"400px\" data-is-descendent-of-query-loop=\"true\" data-show-sale-badge=\"false\" data-width=\"\" class=\"wc-block-components-product-image wc-block-grid__product-image wc-block-components-product-image--aspect-ratio-auto wp-block-woocommerce-product-image\" data-block-type=\"core\"><a href=\"https:\/\/gmz.ltd\/fr\/produit\/gobelets-chauds-en-papier-sans-plastique\/\" data-wp-on--click=\"woocommerce\/product-collection::actions.viewProduct\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/gmz.ltd\/wp-content\/uploads\/2023\/09\/Aqueous-Lined-Paper-Cup.webp\" class=\"attachment-large size-large\" alt=\"Aqueous Lined Paper Cup\" data-testid=\"product-image\" data-image-id=\"20720\" style=\"height:400px;object-fit:cover;\" loading=\"lazy\" srcset=\"https:\/\/gmz.ltd\/wp-content\/uploads\/2023\/09\/Aqueous-Lined-Paper-Cup.webp 1000w, https:\/\/gmz.ltd\/wp-content\/uploads\/2023\/09\/Aqueous-Lined-Paper-Cup-300x300.webp 300w, https:\/\/gmz.ltd\/wp-content\/uploads\/2023\/09\/Aqueous-Lined-Paper-Cup-150x150.webp 150w, https:\/\/gmz.ltd\/wp-content\/uploads\/2023\/09\/Aqueous-Lined-Paper-Cup-768x768.webp 768w, https:\/\/gmz.ltd\/wp-content\/uploads\/2023\/09\/Aqueous-Lined-Paper-Cup-400x400.webp 400w, https:\/\/gmz.ltd\/wp-content\/uploads\/2023\/09\/Aqueous-Lined-Paper-Cup-800x800.webp 800w, https:\/\/gmz.ltd\/wp-content\/uploads\/2023\/09\/Aqueous-Lined-Paper-Cup-100x100.webp 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><div class=\"wc-block-components-product-image__inner-container\"><\/div><\/a><\/div>\n\n<h3 style=\"margin-bottom:0.75rem;margin-top:0\" class=\"has-text-align-center wp-block-post-title has-medium-font-size\" data-block-type=\"core\"><a href=\"https:\/\/gmz.ltd\/fr\/produit\/gobelets-chauds-en-papier-sans-plastique\/\" target=\"_self\" >Gobelets chauds en papier sans plastique<\/a><\/h3>\n\n<div data-block-name=\"woocommerce\/product-button\" data-font-size=\"small\" data-is-descendent-of-query-loop=\"true\" data-text-align=\"center\" class=\"wp-block-button wc-block-components-product-button align-center wp-block-woocommerce-product-button has-small-font-size\"\n\t\t\t\t\t\n\t\t\t\t\tdata-wp-context='{\"quantityToAdd\":1,\"addToCartText\":\"Lire la suite\",\"tempQuantity\":0,\"animationStatus\":\"IDLE\",\"inTheCartText\":\"### dans le panier\",\"noticeId\":\"\",\"hasPressedButton\":false}'\n\t\t\t\t>\n\t\t\t\t\t<a\n\t\t\t\t\t\tclass=\"wp-block-button__link wp-element-button wc-block-components-product-button__button product_type_simple has-font-size has-small-font-size has-text-align-center wc-interactive\"\n\t\t\t\t\t\tstyle=\"\"\n\t\t\t\t\t\thref=\"https:\/\/gmz.ltd\/fr\/produit\/gobelets-chauds-en-papier-sans-plastique\/\" rel=\"nofollow\" data-product_id=\"7847\" data-product_sku=\"\" aria-label=\"En savoir plus sur &ldquo;Gobelets chauds en papier sans plastique&rdquo;\"\n\t\t\t\t\t\tdata-wp-on--click=\"woocommerce\/product-collection::actions.viewProduct\"\n\t\t\t\t\t>\n\t\t\t\t\t<span >Lire la suite<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t<\/div>\n<\/li><\/ul><\/div>\n\n<h3 class=\"wp-block-heading\" id=\"brand-promotion\" data-block-type=\"core\">6. Promotion de la marque<\/h3>\n\n<p class=\"wp-block-paragraph\">L&rsquo;utilisation de gobelets en papier couch\u00e9 PLA pour votre entreprise est \u00e9galement b\u00e9n\u00e9fique pour la promotion de votre marque. Non seulement ces gobelets en papier compostables sont meilleurs pour l&rsquo;environnement, mais vous pouvez \u00e9galement les personnaliser avec votre logo afin d&rsquo;\u00e9largir votre champ d&rsquo;action. Chez GMZ, nous proposons une impression personnalis\u00e9e pour tous nos produits, ce qui signifie que vous pouvez renforcer la promotion de votre marque avec des gobelets brillants que les clients emporteront pour faire la publicit\u00e9 de votre entreprise lors de leurs d\u00e9placements. Vous pouvez choisir le design qui se d\u00e9marque sur vos gobelets et vous r\u00e9jouir de l&rsquo;augmentation du nombre de clients qui franchissent votre porte. GMZ propose une impression personnalis\u00e9e en 8 couleurs diff\u00e9rentes sur la couche ext\u00e9rieure.<\/p>\n\n<figure class=\"wp-block-image size-large\" data-block-type=\"core\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"555\" src=\"https:\/\/gmz.ltd\/wp-content\/uploads\/2023\/12\/custom-pla-coated-paper-cups-1024x555.jpg\" alt=\"gobelets en papier couch&#xE9; personnalis&#xE9;s propos&#xE9;s par GMZ\" class=\"wp-image-3966\" srcset=\"https:\/\/gmz.ltd\/wp-content\/uploads\/2023\/12\/custom-pla-coated-paper-cups-1024x555.jpg 1024w, https:\/\/gmz.ltd\/wp-content\/uploads\/2023\/12\/custom-pla-coated-paper-cups-800x434.jpg 800w, https:\/\/gmz.ltd\/wp-content\/uploads\/2023\/12\/custom-pla-coated-paper-cups-300x163.jpg 300w, https:\/\/gmz.ltd\/wp-content\/uploads\/2023\/12\/custom-pla-coated-paper-cups-768x416.jpg 768w, https:\/\/gmz.ltd\/wp-content\/uploads\/2023\/12\/custom-pla-coated-paper-cups.jpg 1487w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h3 class=\"wp-block-heading\" id=\"boosts-sales\" data-block-type=\"core\">7. Stimuler les ventes<\/h3>\n\n<p class=\"wp-block-paragraph\">De nombreux clients aiment savoir que leurs achats contribuent \u00e0 la protection de l&rsquo;environnement. Si vous utilisez des gobelets en papier compostables PLA et que vous en faites la publicit\u00e9, vous devriez voir vos ventes augmenter. Les gobelets en papier 100 % compostables et biod\u00e9gradables remportent un franc succ\u00e8s aupr\u00e8s des entreprises de boissons. Les clients se sentiront beaucoup plus \u00e0 l&rsquo;aise lorsqu&rsquo;ils ach\u00e8teront un gobelet \u00e0 caf\u00e9 \u00e0 emporter en sachant qu&rsquo;il n&rsquo;augmentera pas la quantit\u00e9 de d\u00e9chets dans les d\u00e9charges et qu&rsquo;il sera \u00e9limin\u00e9 dans les r\u00e8gles de l&rsquo;art.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"are-there-any-problems-with-pla\" data-block-type=\"core\">Y a-t-il des probl\u00e8mes avec l&rsquo;APL ?<\/h2>\n\n<p class=\"wp-block-paragraph\">Bien que les gobelets en papier jetables en PLA soient enti\u00e8rement recyclables et compostables, tous les \u00e9tablissements ne disposent pas de l&rsquo;\u00e9quipement n\u00e9cessaire pour traiter correctement le plastique PLA. Le rev\u00eatement sp\u00e9cial doit d&rsquo;abord \u00eatre enlev\u00e9, puis les mat\u00e9riaux en papier et en plastique du gobelet peuvent \u00eatre recycl\u00e9s s\u00e9par\u00e9ment. Cela signifie que ces gobelets \u00e0 emporter en PLA doivent toujours \u00eatre d\u00e9pos\u00e9s dans les bacs de recyclage appropri\u00e9s, sous peine de contaminer le recyclage. Si l&rsquo;on peut affirmer que les gobelets enduits de PLA sont encore meilleurs pour l&rsquo;environnement en raison de leur caract\u00e8re compostable, il n&rsquo;en reste pas moins qu&rsquo;ils n\u00e9cessitent un processus de recyclage plus important et des \u00e9quipements sp\u00e9cialis\u00e9s pour s&rsquo;assurer qu&rsquo;il est effectu\u00e9 correctement, ce qui consomme \u00e9galement beaucoup d&rsquo;\u00e9nergie et de carburant pour transporter le plastique jusqu&rsquo;aux usines.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"what-is-the-difference-between-pla-and-pe-coating\" data-block-type=\"core\">Quelle est la diff\u00e9rence entre les gobelets en papier couch\u00e9s PLA et PE ?<\/h2>\n\n<p class=\"wp-block-paragraph\">Les rev\u00eatements en plastique PLA et PE sont tous deux largement utilis\u00e9s lors de la production de gobelets en papier pour ajouter de la r\u00e9sistance et de la durabilit\u00e9 aux produits. Les gobelets en papier recouverts de PLA sont 100 % compostables et biod\u00e9gradables. Ils sont fabriqu\u00e9s \u00e0 partir de sources renouvelables telles que la canne \u00e0 sucre et l&rsquo;amidon de ma\u00efs. Cette caract\u00e9ristique fait du PLA une alternative \u00e9cologiquement pr\u00e9f\u00e9rable au PE, qui est d\u00e9riv\u00e9 du p\u00e9trole non renouvelable et n&rsquo;est pas biod\u00e9gradable. Toutefois, les gobelets en papier recouverts de PE sont recyclables, un facteur \u00e0 prendre en compte dans la gestion des d\u00e9chets.<\/p>\n\n<p class=\"wp-block-paragraph\">Les gobelets en papier recouverts de PE sont toujours tr\u00e8s demand\u00e9s, mais plus le nombre de personnes connaissant les avantages incroyables du PLA augmentera, plus son utilisation se g\u00e9n\u00e9ralisera. Les gobelets en papier rev\u00eatus de PLA ont \u00e9t\u00e9 consid\u00e9rablement am\u00e9lior\u00e9s depuis leur invention et, bien qu&rsquo;ils soient fabriqu\u00e9s \u00e0 partir d&rsquo;une source v\u00e9g\u00e9tale renouvelable, ils sont toujours aussi durables et r\u00e9sistants \u00e0 la chaleur que les gobelets en PE. Les gobelets en papier jetables PLA sont id\u00e9aux pour les entreprises de boissons, qu&rsquo;ils soient chauds ou froids. Ils emp\u00eachent les fuites de liquide et isolent le contenu pour qu&rsquo;il reste chaud plus longtemps.<\/p>\n\n<p class=\"wp-block-paragraph\">Le plastique PLA se biod\u00e9grade \u00e9galement beaucoup plus rapidement que le PE. Dans une usine de recyclage sp\u00e9cialis\u00e9e, la d\u00e9composition du PLA \u00e0 une temp\u00e9rature de 50\u00b0c peut prendre un mois, tandis que le compostage du PLA \u00e0 une temp\u00e9rature de 25\u00b0c peut prendre 180 jours.<\/p>\n\n<p class=\"wp-block-paragraph\">Dans l&rsquo;ensemble, les gobelets en papier couch\u00e9 PLA sont une option s\u00fbre, \u00e9cologique et populaire pour votre entreprise de boissons. Ils sont 100 % compostables et biod\u00e9gradables et r\u00e9duiront efficacement l&#8217;empreinte carbone de votre entreprise.<\/p>\n\n<figure class=\"wp-block-table is-style-stripes\" data-block-type=\"core\"><table><thead><tr><th>Fonctionnalit\u00e9<\/th><th>Gobelets en papier avec rev\u00eatement PLA<\/th><th>Gobelets en papier enduit de PE<\/th><\/tr><\/thead><tbody><tr><td><strong>Source mat\u00e9rielle<\/strong><\/td><td>Fabriqu\u00e9 \u00e0 partir de ressources renouvelables comme l&rsquo;amidon de ma\u00efs<\/td><td>Fabriqu\u00e9 \u00e0 partir de ressources non renouvelables \u00e0 base de p\u00e9trole<\/td><\/tr><tr><td><strong>Biod\u00e9gradabilit\u00e9<\/strong><\/td><td>Biod\u00e9gradable dans des conditions de compostage industriel<\/td><td>Non biod\u00e9gradable, mais recyclable<\/td><\/tr><tr><td><strong>Compostabilit\u00e9<\/strong><\/td><td>Compostable dans les installations industrielles<\/td><td>Non compostable<\/td><\/tr><tr><td><strong>R\u00e9sistance \u00e0 l&rsquo;eau<\/strong><\/td><td>Bonne r\u00e9sistance \u00e0 l&rsquo;eau<\/td><td>Excellente r\u00e9sistance \u00e0 l&rsquo;eau<\/td><\/tr><tr><td><strong>R\u00e9sistance \u00e0 la chaleur<\/strong><\/td><td>R\u00e9sistance \u00e0 la chaleur inf\u00e9rieure \u00e0 celle du PE<\/td><td>Meilleure r\u00e9sistance \u00e0 la chaleur<\/td><\/tr><tr><td><strong>Recyclabilit\u00e9<\/strong><\/td><td>Difficile \u00e0 recycler en raison de sa nature compostable<\/td><td>Plus facile \u00e0 recycler dans les installations qui acceptent le PE<\/td><\/tr><tr><td><strong>Impact sur l&rsquo;environnement<\/strong><\/td><td>Empreinte carbone r\u00e9duite, respectueuse de l&rsquo;environnement<\/td><td>Empreinte carbone plus \u00e9lev\u00e9e, moins respectueuse de l&rsquo;environnement<\/td><\/tr><tr><td><strong>Co\u00fbt<\/strong><\/td><td>G\u00e9n\u00e9ralement plus cher<\/td><td>G\u00e9n\u00e9ralement moins cher<\/td><\/tr><tr><td><strong>Utilisation dans les boissons chaudes<\/strong><\/td><td>Convient, mais avec quelques limitations thermiques<\/td><td>Plus adapt\u00e9 aux boissons chaudes<\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Table des mati\u00e8res Qu&rsquo;est-ce que le PLA ? Quels sont les avantages des gobelets en papier couch\u00e9s en PLA ? 1. 100% compostable 2. Biod\u00e9gradable 3. R\u00e9duction de l&#8217;empreinte carbone 4. Isolation et durabilit\u00e9 5. Boire en toute s\u00e9curit\u00e9 6. Promotion de la marque 7. Stimuler les ventes Y a-t-il des probl\u00e8mes avec l&rsquo;APL ? [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6865,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[536],"tags":[264,199],"class_list":["post-8439","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogs-fr","tag-gobelets-en-papier-avec-revetement-pla","tag-gobelets-en-papier-ecologiques"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.5 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Compostable et biod\u00e9gradable : Introduction des gobelets en papier \u00e0 rev\u00eatement PLA - GMZ<\/title>\n<meta name=\"description\" content=\"Qu&#039;est-ce qu&#039;un gobelet en papier couch\u00e9 PLA ? C&#039;est le meilleur gobelet en papier respectueux de l&#039;environnement, 100% compostable et biod\u00e9gradable. Tout savoir sur les gobelets en papier avec rev\u00eatement PLA dans ce blog !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gmz.ltd\/fr\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Compostable et biod\u00e9gradable : Introduction des gobelets en papier \u00e0 rev\u00eatement PLA\" \/>\n<meta property=\"og:description\" content=\"Qu&#039;est-ce qu&#039;un gobelet en papier couch\u00e9 PLA ? C&#039;est le meilleur gobelet en papier respectueux de l&#039;environnement, 100% compostable et biod\u00e9gradable. Tout savoir sur les gobelets en papier avec rev\u00eatement PLA dans ce blog !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gmz.ltd\/fr\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\/\" \/>\n<meta property=\"og:site_name\" content=\"GMZ\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/gmztrade\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-14T16:21:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-13T06:57:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gmz.ltd\/wp-content\/uploads\/2023\/12\/Compostable-Biodegradable-PLA-Coated-Paper-Cups.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"GMZ\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"GMZ\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gmz.ltd\\\/fr\\\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gmz.ltd\\\/fr\\\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\\\/\"},\"author\":{\"name\":\"GMZ\",\"@id\":\"https:\\\/\\\/gmz.ltd\\\/fr\\\/#\\\/schema\\\/person\\\/4503fbf5e183005911e8c853b2ad3a0a\"},\"headline\":\"Compostable et biod\u00e9gradable : Introduction des gobelets en papier \u00e0 rev\u00eatement PLA\",\"datePublished\":\"2023-12-14T16:21:26+00:00\",\"dateModified\":\"2024-08-13T06:57:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gmz.ltd\\\/fr\\\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\\\/\"},\"wordCount\":2103,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gmz.ltd\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gmz.ltd\\\/fr\\\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gmz.ltd\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Compostable-Biodegradable-PLA-Coated-Paper-Cups.jpg\",\"keywords\":[\"Gobelets en papier avec rev\u00eatement PLA\",\"Gobelets en papier \u00e9cologiques\"],\"articleSection\":[\"Blogs\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gmz.ltd\\\/fr\\\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gmz.ltd\\\/fr\\\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\\\/\",\"url\":\"https:\\\/\\\/gmz.ltd\\\/fr\\\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\\\/\",\"name\":\"Compostable et biod\u00e9gradable : Introduction des gobelets en papier \u00e0 rev\u00eatement PLA - GMZ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gmz.ltd\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gmz.ltd\\\/fr\\\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gmz.ltd\\\/fr\\\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gmz.ltd\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Compostable-Biodegradable-PLA-Coated-Paper-Cups.jpg\",\"datePublished\":\"2023-12-14T16:21:26+00:00\",\"dateModified\":\"2024-08-13T06:57:57+00:00\",\"description\":\"Qu'est-ce qu'un gobelet en papier couch\u00e9 PLA ? C'est le meilleur gobelet en papier respectueux de l'environnement, 100% compostable et biod\u00e9gradable. Tout savoir sur les gobelets en papier avec rev\u00eatement PLA dans ce blog !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gmz.ltd\\\/fr\\\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gmz.ltd\\\/fr\\\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/gmz.ltd\\\/fr\\\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gmz.ltd\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Compostable-Biodegradable-PLA-Coated-Paper-Cups.jpg\",\"contentUrl\":\"https:\\\/\\\/gmz.ltd\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Compostable-Biodegradable-PLA-Coated-Paper-Cups.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gmz.ltd\\\/fr\\\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"maison\",\"item\":\"https:\\\/\\\/gmz.ltd\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Compostable et biod\u00e9gradable : Introduction des gobelets en papier \u00e0 rev\u00eatement PLA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gmz.ltd\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/gmz.ltd\\\/fr\\\/\",\"name\":\"GMZ\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/gmz.ltd\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gmz.ltd\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gmz.ltd\\\/fr\\\/#organization\",\"name\":\"GMZ\",\"url\":\"https:\\\/\\\/gmz.ltd\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/gmz.ltd\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gmz.ltd\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/gmzpack.svg\",\"contentUrl\":\"https:\\\/\\\/gmz.ltd\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/gmzpack.svg\",\"width\":170,\"height\":79,\"caption\":\"GMZ\"},\"image\":{\"@id\":\"https:\\\/\\\/gmz.ltd\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gmz.ltd\\\/fr\\\/#\\\/schema\\\/person\\\/4503fbf5e183005911e8c853b2ad3a0a\",\"name\":\"GMZ\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6910fd40711f82a1c4b876cbc019eb9a9382c7ebd90649fe8ae23525ebe098ca?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6910fd40711f82a1c4b876cbc019eb9a9382c7ebd90649fe8ae23525ebe098ca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6910fd40711f82a1c4b876cbc019eb9a9382c7ebd90649fe8ae23525ebe098ca?s=96&d=mm&r=g\",\"caption\":\"GMZ\"},\"description\":\"We are a family B2B business from China, focusing on the production and export of food packaging for more than 17 years. We design, produce and deliver paper cups, PET cups and food containers to customers worldwide.\",\"sameAs\":[\"https:\\\/\\\/gmz.ltd\",\"https:\\\/\\\/www.facebook.com\\\/gmztrade\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/gmz-ltd\\\/\"],\"url\":\"https:\\\/\\\/gmz.ltd\\\/fr\\\/author\\\/whgmz2021\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Compostable et biod\u00e9gradable : Introduction des gobelets en papier \u00e0 rev\u00eatement PLA - GMZ","description":"Qu'est-ce qu'un gobelet en papier couch\u00e9 PLA ? C'est le meilleur gobelet en papier respectueux de l'environnement, 100% compostable et biod\u00e9gradable. Tout savoir sur les gobelets en papier avec rev\u00eatement PLA dans ce blog !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gmz.ltd\/fr\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\/","og_locale":"fr_FR","og_type":"article","og_title":"Compostable et biod\u00e9gradable : Introduction des gobelets en papier \u00e0 rev\u00eatement PLA","og_description":"Qu'est-ce qu'un gobelet en papier couch\u00e9 PLA ? C'est le meilleur gobelet en papier respectueux de l'environnement, 100% compostable et biod\u00e9gradable. Tout savoir sur les gobelets en papier avec rev\u00eatement PLA dans ce blog !","og_url":"https:\/\/gmz.ltd\/fr\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\/","og_site_name":"GMZ","article_author":"https:\/\/www.facebook.com\/gmztrade","article_published_time":"2023-12-14T16:21:26+00:00","article_modified_time":"2024-08-13T06:57:57+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/gmz.ltd\/wp-content\/uploads\/2023\/12\/Compostable-Biodegradable-PLA-Coated-Paper-Cups.jpg","type":"image\/jpeg"}],"author":"GMZ","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"GMZ","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gmz.ltd\/fr\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\/#article","isPartOf":{"@id":"https:\/\/gmz.ltd\/fr\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\/"},"author":{"name":"GMZ","@id":"https:\/\/gmz.ltd\/fr\/#\/schema\/person\/4503fbf5e183005911e8c853b2ad3a0a"},"headline":"Compostable et biod\u00e9gradable : Introduction des gobelets en papier \u00e0 rev\u00eatement PLA","datePublished":"2023-12-14T16:21:26+00:00","dateModified":"2024-08-13T06:57:57+00:00","mainEntityOfPage":{"@id":"https:\/\/gmz.ltd\/fr\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\/"},"wordCount":2103,"commentCount":0,"publisher":{"@id":"https:\/\/gmz.ltd\/fr\/#organization"},"image":{"@id":"https:\/\/gmz.ltd\/fr\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\/#primaryimage"},"thumbnailUrl":"https:\/\/gmz.ltd\/wp-content\/uploads\/2023\/12\/Compostable-Biodegradable-PLA-Coated-Paper-Cups.jpg","keywords":["Gobelets en papier avec rev\u00eatement PLA","Gobelets en papier \u00e9cologiques"],"articleSection":["Blogs"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gmz.ltd\/fr\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gmz.ltd\/fr\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\/","url":"https:\/\/gmz.ltd\/fr\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\/","name":"Compostable et biod\u00e9gradable : Introduction des gobelets en papier \u00e0 rev\u00eatement PLA - GMZ","isPartOf":{"@id":"https:\/\/gmz.ltd\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gmz.ltd\/fr\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\/#primaryimage"},"image":{"@id":"https:\/\/gmz.ltd\/fr\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\/#primaryimage"},"thumbnailUrl":"https:\/\/gmz.ltd\/wp-content\/uploads\/2023\/12\/Compostable-Biodegradable-PLA-Coated-Paper-Cups.jpg","datePublished":"2023-12-14T16:21:26+00:00","dateModified":"2024-08-13T06:57:57+00:00","description":"Qu'est-ce qu'un gobelet en papier couch\u00e9 PLA ? C'est le meilleur gobelet en papier respectueux de l'environnement, 100% compostable et biod\u00e9gradable. Tout savoir sur les gobelets en papier avec rev\u00eatement PLA dans ce blog !","breadcrumb":{"@id":"https:\/\/gmz.ltd\/fr\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gmz.ltd\/fr\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/gmz.ltd\/fr\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\/#primaryimage","url":"https:\/\/gmz.ltd\/wp-content\/uploads\/2023\/12\/Compostable-Biodegradable-PLA-Coated-Paper-Cups.jpg","contentUrl":"https:\/\/gmz.ltd\/wp-content\/uploads\/2023\/12\/Compostable-Biodegradable-PLA-Coated-Paper-Cups.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/gmz.ltd\/fr\/compostable-et-biodegradable-introduction-des-gobelets-en-papier-a-revetement-pla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"maison","item":"https:\/\/gmz.ltd\/fr\/"},{"@type":"ListItem","position":2,"name":"Compostable et biod\u00e9gradable : Introduction des gobelets en papier \u00e0 rev\u00eatement PLA"}]},{"@type":"WebSite","@id":"https:\/\/gmz.ltd\/fr\/#website","url":"https:\/\/gmz.ltd\/fr\/","name":"GMZ","description":"","publisher":{"@id":"https:\/\/gmz.ltd\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gmz.ltd\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/gmz.ltd\/fr\/#organization","name":"GMZ","url":"https:\/\/gmz.ltd\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/gmz.ltd\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/gmz.ltd\/wp-content\/uploads\/2024\/11\/gmzpack.svg","contentUrl":"https:\/\/gmz.ltd\/wp-content\/uploads\/2024\/11\/gmzpack.svg","width":170,"height":79,"caption":"GMZ"},"image":{"@id":"https:\/\/gmz.ltd\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/gmz.ltd\/fr\/#\/schema\/person\/4503fbf5e183005911e8c853b2ad3a0a","name":"GMZ","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/6910fd40711f82a1c4b876cbc019eb9a9382c7ebd90649fe8ae23525ebe098ca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6910fd40711f82a1c4b876cbc019eb9a9382c7ebd90649fe8ae23525ebe098ca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6910fd40711f82a1c4b876cbc019eb9a9382c7ebd90649fe8ae23525ebe098ca?s=96&d=mm&r=g","caption":"GMZ"},"description":"We are a family B2B business from China, focusing on the production and export of food packaging for more than 17 years. We design, produce and deliver paper cups, PET cups and food containers to customers worldwide.","sameAs":["https:\/\/gmz.ltd","https:\/\/www.facebook.com\/gmztrade","https:\/\/www.linkedin.com\/company\/gmz-ltd\/"],"url":"https:\/\/gmz.ltd\/fr\/author\/whgmz2021\/"}]}},"_links":{"self":[{"href":"https:\/\/gmz.ltd\/fr\/wp-json\/wp\/v2\/posts\/8439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gmz.ltd\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gmz.ltd\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gmz.ltd\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gmz.ltd\/fr\/wp-json\/wp\/v2\/comments?post=8439"}],"version-history":[{"count":3,"href":"https:\/\/gmz.ltd\/fr\/wp-json\/wp\/v2\/posts\/8439\/revisions"}],"predecessor-version":[{"id":14093,"href":"https:\/\/gmz.ltd\/fr\/wp-json\/wp\/v2\/posts\/8439\/revisions\/14093"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gmz.ltd\/fr\/wp-json\/wp\/v2\/media\/6865"}],"wp:attachment":[{"href":"https:\/\/gmz.ltd\/fr\/wp-json\/wp\/v2\/media?parent=8439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gmz.ltd\/fr\/wp-json\/wp\/v2\/categories?post=8439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gmz.ltd\/fr\/wp-json\/wp\/v2\/tags?post=8439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}